{"id":14719,"date":"2026-01-19T14:58:12","date_gmt":"2026-01-19T12:58:12","guid":{"rendered":"https:\/\/visitoulu.fi\/?p=14719"},"modified":"2026-01-19T14:58:13","modified_gmt":"2026-01-19T12:58:13","slug":"entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026","status":"publish","type":"post","link":"https:\/\/visitoulu.fi\/en\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\/","title":{"rendered":"Entdecken Sie Oulu: Von einer Stadt im fernen Norden zu einem der besten Reiseziele der Welt im Jahr 2026"},"content":{"rendered":"\n<p>Die Welt richtet ihren Blick gen Norden: Oulu r\u00fcckt als Europas Kulturhauptstadt 2026 ins Rampenlicht. Von National Geographic, BBC, Forbes und Cond\u00e9 Nast Traveler hervorgehoben, z\u00e4hlt Oulu zu den Top-Reisezielen weltweit f\u00fcr 2026. Von schwimmenden Saunen und Luftgitarren bis hin zu Festivals auf zugefrorenen Meeren und arktischem Licht \u2013 lesen Sie weiter und entdecken Sie, warum Oulu unbedingt auf Ihre Reiseliste geh\u00f6rt!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Welt richtet ihren Blick gen Norden: Oulu r\u00fcckt als Europas Kulturhauptstadt 2026 ins Rampenlicht. Von National Geographic, BBC, Forbes und Cond\u00e9 Nast Traveler hervorgehoben, z\u00e4hlt Oulu zu den Top-Reisezielen weltweit f\u00fcr 2026. Von schwimmenden Saunen und Luftgitarren bis hin zu Festivals auf zugefrorenen Meeren und arktischem Licht \u2013 lesen Sie weiter und entdecken Sie, [&#8230;]<\/p>\n<p><a class=\"btn btn-secondary understrap-read-more-link\" href=\"https:\/\/visitoulu.fi\/en\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\/\">Read More&#8230;<span class=\"screen-reader-text\"> from Entdecken Sie Oulu: Von einer Stadt im fernen Norden zu einem der besten Reiseziele der Welt im Jahr 2026<\/span><\/a><\/p>\n","protected":false},"author":32,"featured_media":14702,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[2],"tags":[],"coauthors":[195],"class_list":["post-14719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entdecken Sie Oulu: Von einer Stadt im fernen Norden zu einem der besten Reiseziele der Welt im Jahr 2026 - Visit Oulu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/visitoulu.fi\/en\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entdecken Sie Oulu: Von einer Stadt im fernen Norden zu einem der besten Reiseziele der Welt im Jahr 2026 - Visit Oulu\" \/>\n<meta property=\"og:description\" content=\"Die Welt richtet ihren Blick gen Norden: Oulu r\u00fcckt als Europas Kulturhauptstadt 2026 ins Rampenlicht. Von National Geographic, BBC, Forbes und Cond\u00e9 Nast Traveler hervorgehoben, z\u00e4hlt Oulu zu den Top-Reisezielen weltweit f\u00fcr 2026. Von schwimmenden Saunen und Luftgitarren bis hin zu Festivals auf zugefrorenen Meeren und arktischem Licht \u2013 lesen Sie weiter und entdecken Sie, [...]Read More... from Entdecken Sie Oulu: Von einer Stadt im fernen Norden zu einem der besten Reiseziele der Welt im Jahr 2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/visitoulu.fi\/en\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Visit Oulu\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-19T12:58:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-19T12:58:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/visitoulu.fi\/wp-content\/uploads\/2026\/01\/Tori_Paikoillanne_valmiit_Oulu_Oulu2026_Avajaiset_1601_Henri_Luoma_03-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rosa Ruuskanen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rosa Ruuskanen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\\\/\"},\"author\":{\"name\":\"Rosa Ruuskanen\",\"@id\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/#\\\/schema\\\/person\\\/b8e5a4a1f07dd73554ffbbe2b8e8dc58\"},\"headline\":\"Entdecken Sie Oulu: Von einer Stadt im fernen Norden zu einem der besten Reiseziele der Welt im Jahr 2026\",\"datePublished\":\"2026-01-19T12:58:12+00:00\",\"dateModified\":\"2026-01-19T12:58:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\\\/\"},\"wordCount\":81,\"image\":{\"@id\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitoulu.fi\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Tori_Paikoillanne_valmiit_Oulu_Oulu2026_Avajaiset_1601_Henri_Luoma_03-scaled.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\\\/\",\"url\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\\\/\",\"name\":\"Entdecken Sie Oulu: Von einer Stadt im fernen Norden zu einem der besten Reiseziele der Welt im Jahr 2026 - Visit Oulu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/visitoulu.fi\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Tori_Paikoillanne_valmiit_Oulu_Oulu2026_Avajaiset_1601_Henri_Luoma_03-scaled.jpg\",\"datePublished\":\"2026-01-19T12:58:12+00:00\",\"dateModified\":\"2026-01-19T12:58:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/#\\\/schema\\\/person\\\/b8e5a4a1f07dd73554ffbbe2b8e8dc58\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/visitoulu.fi\\\/en\\\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/visitoulu.fi\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Tori_Paikoillanne_valmiit_Oulu_Oulu2026_Avajaiset_1601_Henri_Luoma_03-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/visitoulu.fi\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/Tori_Paikoillanne_valmiit_Oulu_Oulu2026_Avajaiset_1601_Henri_Luoma_03-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Oulu2026 Opening Festival, On your marks, get set, Oulu!, Market Square. Photographer: Henri Luoma\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entdecken Sie Oulu: Von einer Stadt im fernen Norden zu einem der besten Reiseziele der Welt im Jahr 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/\",\"name\":\"Visit Oulu\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/#\\\/schema\\\/person\\\/b8e5a4a1f07dd73554ffbbe2b8e8dc58\",\"name\":\"Rosa Ruuskanen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ccc3f3faaf914d7086285c9a5914ab5034c81ccd25f3274a6f036ce798271ae7?s=96&d=mm&r=gc5227ba7c3f401aa50ca43e56399553f\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ccc3f3faaf914d7086285c9a5914ab5034c81ccd25f3274a6f036ce798271ae7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ccc3f3faaf914d7086285c9a5914ab5034c81ccd25f3274a6f036ce798271ae7?s=96&d=mm&r=g\",\"caption\":\"Rosa Ruuskanen\"},\"url\":\"https:\\\/\\\/visitoulu.fi\\\/en\\\/author\\\/rosavisitoulu-fi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entdecken Sie Oulu: Von einer Stadt im fernen Norden zu einem der besten Reiseziele der Welt im Jahr 2026 - Visit Oulu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/visitoulu.fi\/en\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\/","og_locale":"en_US","og_type":"article","og_title":"Entdecken Sie Oulu: Von einer Stadt im fernen Norden zu einem der besten Reiseziele der Welt im Jahr 2026 - Visit Oulu","og_description":"Die Welt richtet ihren Blick gen Norden: Oulu r\u00fcckt als Europas Kulturhauptstadt 2026 ins Rampenlicht. Von National Geographic, BBC, Forbes und Cond\u00e9 Nast Traveler hervorgehoben, z\u00e4hlt Oulu zu den Top-Reisezielen weltweit f\u00fcr 2026. Von schwimmenden Saunen und Luftgitarren bis hin zu Festivals auf zugefrorenen Meeren und arktischem Licht \u2013 lesen Sie weiter und entdecken Sie, [...]Read More... from Entdecken Sie Oulu: Von einer Stadt im fernen Norden zu einem der besten Reiseziele der Welt im Jahr 2026","og_url":"https:\/\/visitoulu.fi\/en\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\/","og_site_name":"Visit Oulu","article_published_time":"2026-01-19T12:58:12+00:00","article_modified_time":"2026-01-19T12:58:13+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/visitoulu.fi\/wp-content\/uploads\/2026\/01\/Tori_Paikoillanne_valmiit_Oulu_Oulu2026_Avajaiset_1601_Henri_Luoma_03-scaled.jpg","type":"image\/jpeg"}],"author":"Rosa Ruuskanen","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Rosa Ruuskanen","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/visitoulu.fi\/en\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\/#article","isPartOf":{"@id":"https:\/\/visitoulu.fi\/en\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\/"},"author":{"name":"Rosa Ruuskanen","@id":"https:\/\/visitoulu.fi\/en\/#\/schema\/person\/b8e5a4a1f07dd73554ffbbe2b8e8dc58"},"headline":"Entdecken Sie Oulu: Von einer Stadt im fernen Norden zu einem der besten Reiseziele der Welt im Jahr 2026","datePublished":"2026-01-19T12:58:12+00:00","dateModified":"2026-01-19T12:58:13+00:00","mainEntityOfPage":{"@id":"https:\/\/visitoulu.fi\/en\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\/"},"wordCount":81,"image":{"@id":"https:\/\/visitoulu.fi\/en\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/visitoulu.fi\/wp-content\/uploads\/2026\/01\/Tori_Paikoillanne_valmiit_Oulu_Oulu2026_Avajaiset_1601_Henri_Luoma_03-scaled.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/visitoulu.fi\/en\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\/","url":"https:\/\/visitoulu.fi\/en\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\/","name":"Entdecken Sie Oulu: Von einer Stadt im fernen Norden zu einem der besten Reiseziele der Welt im Jahr 2026 - Visit Oulu","isPartOf":{"@id":"https:\/\/visitoulu.fi\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/visitoulu.fi\/en\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\/#primaryimage"},"image":{"@id":"https:\/\/visitoulu.fi\/en\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/visitoulu.fi\/wp-content\/uploads\/2026\/01\/Tori_Paikoillanne_valmiit_Oulu_Oulu2026_Avajaiset_1601_Henri_Luoma_03-scaled.jpg","datePublished":"2026-01-19T12:58:12+00:00","dateModified":"2026-01-19T12:58:13+00:00","author":{"@id":"https:\/\/visitoulu.fi\/en\/#\/schema\/person\/b8e5a4a1f07dd73554ffbbe2b8e8dc58"},"breadcrumb":{"@id":"https:\/\/visitoulu.fi\/en\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/visitoulu.fi\/en\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/visitoulu.fi\/en\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\/#primaryimage","url":"https:\/\/visitoulu.fi\/wp-content\/uploads\/2026\/01\/Tori_Paikoillanne_valmiit_Oulu_Oulu2026_Avajaiset_1601_Henri_Luoma_03-scaled.jpg","contentUrl":"https:\/\/visitoulu.fi\/wp-content\/uploads\/2026\/01\/Tori_Paikoillanne_valmiit_Oulu_Oulu2026_Avajaiset_1601_Henri_Luoma_03-scaled.jpg","width":2560,"height":1707,"caption":"Oulu2026 Opening Festival, On your marks, get set, Oulu!, Market Square. Photographer: Henri Luoma"},{"@type":"BreadcrumbList","@id":"https:\/\/visitoulu.fi\/en\/entdecken-sie-oulu-von-einer-stadt-im-fernen-norden-zu-einem-der-besten-reiseziele-der-welt-im-jahr-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/visitoulu.fi\/en\/"},{"@type":"ListItem","position":2,"name":"Entdecken Sie Oulu: Von einer Stadt im fernen Norden zu einem der besten Reiseziele der Welt im Jahr 2026"}]},{"@type":"WebSite","@id":"https:\/\/visitoulu.fi\/en\/#website","url":"https:\/\/visitoulu.fi\/en\/","name":"Visit Oulu","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/visitoulu.fi\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/visitoulu.fi\/en\/#\/schema\/person\/b8e5a4a1f07dd73554ffbbe2b8e8dc58","name":"Rosa Ruuskanen","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/ccc3f3faaf914d7086285c9a5914ab5034c81ccd25f3274a6f036ce798271ae7?s=96&d=mm&r=gc5227ba7c3f401aa50ca43e56399553f","url":"https:\/\/secure.gravatar.com\/avatar\/ccc3f3faaf914d7086285c9a5914ab5034c81ccd25f3274a6f036ce798271ae7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ccc3f3faaf914d7086285c9a5914ab5034c81ccd25f3274a6f036ce798271ae7?s=96&d=mm&r=g","caption":"Rosa Ruuskanen"},"url":"https:\/\/visitoulu.fi\/en\/author\/rosavisitoulu-fi\/"}]}},"_links":{"self":[{"href":"https:\/\/visitoulu.fi\/en\/wp-json\/wp\/v2\/posts\/14719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visitoulu.fi\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/visitoulu.fi\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/visitoulu.fi\/en\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/visitoulu.fi\/en\/wp-json\/wp\/v2\/comments?post=14719"}],"version-history":[{"count":4,"href":"https:\/\/visitoulu.fi\/en\/wp-json\/wp\/v2\/posts\/14719\/revisions"}],"predecessor-version":[{"id":14723,"href":"https:\/\/visitoulu.fi\/en\/wp-json\/wp\/v2\/posts\/14719\/revisions\/14723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visitoulu.fi\/en\/wp-json\/wp\/v2\/media\/14702"}],"wp:attachment":[{"href":"https:\/\/visitoulu.fi\/en\/wp-json\/wp\/v2\/media?parent=14719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visitoulu.fi\/en\/wp-json\/wp\/v2\/categories?post=14719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visitoulu.fi\/en\/wp-json\/wp\/v2\/tags?post=14719"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/visitoulu.fi\/en\/wp-json\/wp\/v2\/coauthors?post=14719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}